{"id":4618,"date":"2023-01-05T14:11:43","date_gmt":"2023-01-05T14:11:43","guid":{"rendered":"http:\/\/20032023.lipo-clinic.events\/page-daccueil\/"},"modified":"2026-04-23T14:06:53","modified_gmt":"2026-04-23T14:06:53","slug":"page-daccueil","status":"publish","type":"page","link":"https:\/\/www.lipo.clinic\/fr\/","title":{"rendered":"Page d&#8217;accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4618\" class=\"elementor elementor-4618 elementor-149\" data-elementor-post-type=\"page\">\n\t\t\t\t<section class=\"elementor-element elementor-element-6666852 e-con-full e-flex e-con e-parent\" data-id=\"6666852\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a42185a elementor-widget elementor-widget-heading\" data-id=\"a42185a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Connu de :<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0bc1ae elementor-grid-6 elementor-grid-tablet-6 elementor-grid-mobile-3 elementor-widget elementor-widget-pp-logo-grid\" data-id=\"c0bc1ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-logo-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-logo-grid elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item elementor-repeater-item-f8eef62\">\n\t\t\t\t\t\t<div class=\"pp-logo-wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2025\/10\/RTL-1.png\" alt=\"Logo von RTL, einem der bekanntesten Fernsehsender in Deutschland, auf schwarzem Hintergrund. Das Design zeigt die Buchstaben R, T und L in markanter, moderner Schriftart.\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item elementor-repeater-item-c750141\">\n\t\t\t\t\t\t<div class=\"pp-logo-wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2025\/10\/WDR-1.png\" alt=\"Schwarz-wei\u00dfes Symbol einer Gl\u00fchbirne, das Kreativit\u00e4t und innovative Ideen darstellt. Ideal f\u00fcr Inhalte \u00fcber Inspiration, Design und Technologie.\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item elementor-repeater-item-cb9d279\">\n\t\t\t\t\t\t<div class=\"pp-logo-wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2025\/10\/Hamburger-Abendblatt-1.png\" alt=\"Logo des Hamburger Abendblatts, einer bekannten deutschen Tageszeitung, das in einer klassischen Schriftart gestaltet ist.\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item elementor-repeater-item-624e94d\">\n\t\t\t\t\t\t<div class=\"pp-logo-wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2025\/10\/SWR-1.png\" alt=\"Logo des SWR, einem regionalen Rundfunkanbieter in Deutschland, das f\u00fcr seine vielf\u00e4ltigen Programme und Informationsangebote bekannt ist.\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item elementor-repeater-item-794ed3a\">\n\t\t\t\t\t\t<div class=\"pp-logo-wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2025\/10\/Sat.1-1.png\" alt=\"Logo von SAT.1, einem deutschen Fernsehsender, dargestellt als stilisierte Kugel in Schwarz und Wei\u00df mit dem Schriftzug &quot;SAT.1&quot; daneben.\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item elementor-repeater-item-91aabd1\">\n\t\t\t\t\t\t<div class=\"pp-logo-wrap\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2025\/10\/RTL2-1.png\" alt=\"Minimalistisches Logo eines Unternehmens, das moderne Design-Elemente verwendet und auf einem wei\u00dfen Hintergrund dargestellt ist. Perfekt f\u00fcr Branding und Marketingzwecke.\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-43976ce e-con-full sectionoverflow e-flex e-con e-parent\" data-id=\"43976ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-69777bd e-con-full e-flex e-con e-child\" data-id=\"69777bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dd92ea elementor-widget elementor-widget-heading\" data-id=\"7dd92ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">La principale clinique du lip\u0153d\u00e8me pour le diagnostic et le traitement du lip\u0153d\u00e8me  <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4537b4a elementor-widget elementor-widget-heading\" data-id=\"4537b4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nouvelle libert\u00e9 <br>pour le corps et l'esprit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98e1ad4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"98e1ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Environ une femme sur dix est touch\u00e9e par le <a href=\"https:\/\/www.lipo.clinic\/fr\/?page_id=4636#was\" data-uw-rm-brl=\"PR\" data-uw-original-href=\"https:\/\/www.lipo.clinic\/fr\/?page_id=4636#was\">lip\u0153d\u00e8me<\/a> \u2013 une \u00ab maladie que tout le monde voit, mais que presque personne ne conna\u00eet \u00bb.<\/p>\n<p>Pionni\u00e8re dans le traitement chirurgical du lip\u0153d\u00e8me, la <a href=\"\/?page_id=1869\" data-uw-rm-brl=\"PR\" data-uw-original-href=\"https:\/\/www.lipo.clinic\/fr\/nos-cliniques\/\">LipoClinic<\/a> est la premi\u00e8re clinique sp\u00e9cialis\u00e9e dans le lip\u0153d\u00e8me au monde, avec plus de 2500 op\u00e9rations r\u00e9alis\u00e9es avec succ\u00e8s chaque ann\u00e9e, et se distingue par son concept de traitement \u00e9prouv\u00e9.<\/p>\n<p>Nous sensibilisons la soci\u00e9t\u00e9 \u00e0 la souffrance physique et morale des personnes concern\u00e9es, nous nous engageons pour que <a href=\"\/?page_id=1782#anerkennung\" data-uw-rm-brl=\"PR\" data-uw-original-href=\"https:\/\/www.lipo.clinic\/fr\/notre-approche\/#anerkennung\">le lip\u0153d\u00e8me soit reconnu comme une maladie<\/a> et nous luttons contre le lip\u0153d\u00e8me en tant que clinique priv\u00e9e dans le monde entier.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-046f09b e-con-full respfullwidth e-flex e-con e-child\" data-id=\"046f09b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2.8,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-3753e42 e-con-full e-flex e-con e-parent\" data-id=\"3753e42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-953a829 elementor-widget elementor-widget-heading\" data-id=\"953a829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">En tant que sp\u00e9cialistes du traitement du lip\u0153d\u00e8me, nous nous engageons \u00e0 ce que le lip\u0153d\u00e8me soit reconnu comme une maladie dans le monde entier et nous d\u00e9veloppons en permanence notre approche globale de la chirurgie et du traitement afin de permettre au plus grand nombre de femmes possible de r\u00e9duire significativement leurs douleurs et d'am\u00e9liorer leur qualit\u00e9 de vie.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9c19088 e-flex e-con-boxed e-con e-parent\" data-id=\"9c19088\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb70ee0 elementor-widget elementor-widget-heading\" data-id=\"cb70ee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Exp\u00e9riences de nos patients<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-038f90b elementor-widget elementor-widget-html\" data-id=\"038f90b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Elfsight Google Reviews | Untitled Google Reviews 2 -->\r\n<script src=\"https:\/\/elfsightcdn.com\/platform.js\" async=\"\"><\/script>\r\n<div class=\"elfsight-app-395e007b-c108-4535-bb4e-306cbe7af926\" data-elfsight-app-lazy=\"\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<section class=\"elementor-element elementor-element-71a940c e-con-full cardwrap e-flex e-con e-parent\" data-id=\"71a940c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4c5ad87 e-con-full e-flex e-con e-child\" data-id=\"4c5ad87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aec5a52 elementor-widget elementor-widget-heading\" data-id=\"aec5a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LE LIP\u0152D\u00c8ME<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d78bd1 elementor-widget elementor-widget-heading\" data-id=\"6d78bd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Une charge corporelle et psychique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9cc31 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4b9cc31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Le lip\u0153d\u00e8me est un trouble pathologique de la r\u00e9partition des cellules adipeuses<\/strong> provoquant une sensibilit\u00e9 \u00e0 la pression et des sensations de tension. Les m\u00e9decins et chercheurs pr\u00e9sument actuellement que des changements hormonaux, comme pendant la pubert\u00e9 ou une grossesse sont \u00e0 l\u2019origine de 85 % des cas de lip\u0153d\u00e8me.  Une pr\u00e9disposition h\u00e9r\u00e9ditaire compte \u00e9galement parmi les causes possibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aab8251 e-con-full cardholder e-flex e-con e-child\" data-id=\"aab8251\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c12237a e-flex e-con-boxed e-con e-child\" data-id=\"c12237a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<article class=\"elementor-element elementor-element-9757972 cardstyle e-con-full e-flex e-con e-child\" data-id=\"9757972\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a830af e-con-full e-flex e-con e-child\" data-id=\"2a830af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-477739f cardimage elementor-widget elementor-widget-image\" data-id=\"477739f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2024\/02\/20231201_CG_LIPOCLINIC_0699-1024x683.jpg\" class=\"attachment-large size-large wp-image-9650\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2024\/02\/20231201_CG_LIPOCLINIC_0699-1024x683.jpg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2024\/02\/20231201_CG_LIPOCLINIC_0699-300x200.jpg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2024\/02\/20231201_CG_LIPOCLINIC_0699-768x512.jpg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2024\/02\/20231201_CG_LIPOCLINIC_0699-1536x1024.jpg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2024\/02\/20231201_CG_LIPOCLINIC_0699-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0215809 elementor-widget elementor-widget-heading\" data-id=\"0215809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Qu\u2019est-ce qu\u2019un lip\u0153d\u00e8me ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d38b88a elementor-widget elementor-widget-text-editor\" data-id=\"d38b88a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Le lip\u0153d\u00e8me se manifeste par un accroissement incontr\u00f4l\u00e9 du tissu adipeux sous-cutan\u00e9 chronique, une condition souvent h\u00e9rit\u00e9e et probablement d\u00e9clench\u00e9e par les hormones f\u00e9minines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40c078b cardbtn elementor-widget elementor-widget-button\" data-id=\"40c078b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/das-lipodem\/#was\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69f87a1 e-flex e-con-boxed e-con e-child\" data-id=\"69f87a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<article class=\"elementor-element elementor-element-6636b37 cardstyle e-con-full e-flex e-con e-child\" data-id=\"6636b37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-abc95b4 e-con-full e-flex e-con e-child\" data-id=\"abc95b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4729c11 cardimage elementor-widget elementor-widget-image\" data-id=\"4729c11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/8433466-1024x683.jpg\" class=\"attachment-large size-large wp-image-4469\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/8433466-1024x683.jpg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/8433466-300x200.jpg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/8433466-768x512.jpg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/8433466-1536x1024.jpg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/8433466-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7740413 elementor-widget elementor-widget-heading\" data-id=\"7740413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quels sont les sympt\u00f4mes d\u2019un lip\u0153d\u00e8me ? <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b1702 elementor-widget elementor-widget-text-editor\" data-id=\"24b1702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En raison de ses manifestations et sa ressemblance avec d\u2019autres maladies, il est souvent difficile de d\u00e9terminer avec certitude un lip\u0153d\u00e8me sur la base de ses sympt\u00f4mes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5859081 cardbtn elementor-widget elementor-widget-button\" data-id=\"5859081\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/das-lipodem\/#symptome\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91d691d e-flex e-con-boxed e-con e-child\" data-id=\"91d691d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<article class=\"elementor-element elementor-element-577c11c cardstyle e-con-full e-flex e-con e-child\" data-id=\"577c11c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-35040be e-con-full e-flex e-con e-child\" data-id=\"35040be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52a7946 cardimage elementor-widget elementor-widget-image\" data-id=\"52a7946\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/136454179-1024x683.jpeg\" class=\"attachment-large size-large wp-image-4458\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/136454179-1024x683.jpeg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/136454179-300x200.jpeg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/136454179-768x512.jpeg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/136454179-1536x1024.jpeg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/136454179-2048x1365.jpeg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-963259e elementor-widget elementor-widget-heading\" data-id=\"963259e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ai-je un lip\u0153d\u00e8me ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dd0957 elementor-widget elementor-widget-text-editor\" data-id=\"7dd0957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un premier test peut vous aider \u00e0 d\u00e9terminer si vous \u00eates \u00e9ventuellement touch\u00e9e par un lip\u0153d\u00e8me. Cliquez ici pour d\u00e9marrer le test.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd3bb0 cardbtn elementor-widget elementor-widget-button\" data-id=\"6cd3bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/fr\/test-du-lipoedeme\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-afe0f15 e-con-full cardholder e-flex e-con e-child\" data-id=\"afe0f15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f0bde06 e-flex e-con-boxed e-con e-child\" data-id=\"f0bde06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<article class=\"elementor-element elementor-element-40f8a7a cardstyle e-con-full e-flex e-con e-child\" data-id=\"40f8a7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ba21dee e-con-full e-flex e-con e-child\" data-id=\"ba21dee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d40d325 cardimage elementor-widget elementor-widget-image\" data-id=\"d40d325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/pexels-sora-shimazaki-5668869-1024x683.jpg\" class=\"attachment-large size-large wp-image-4451\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/pexels-sora-shimazaki-5668869-1024x683.jpg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/pexels-sora-shimazaki-5668869-300x200.jpg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/pexels-sora-shimazaki-5668869-768x512.jpg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/pexels-sora-shimazaki-5668869-1536x1024.jpg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/pexels-sora-shimazaki-5668869.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e01604 elementor-widget elementor-widget-heading\" data-id=\"4e01604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quels sont les diff\u00e9rents stades et types de lip\u0153d\u00e8me ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b4fc9 elementor-widget elementor-widget-text-editor\" data-id=\"d2b4fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Comme le lip\u0153d\u00e8me est un trouble de la r\u00e9partition des cellules adipeuses chronique et \u00e9volutive, il se classe en diff\u00e9rents stades et types.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c582bab cardbtn elementor-widget elementor-widget-button\" data-id=\"c582bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/das-lipodem\/#stadien\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9995331 e-flex e-con-boxed e-con e-child\" data-id=\"9995331\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<article class=\"elementor-element elementor-element-b3d777d cardstyle e-con-full e-flex e-con e-child\" data-id=\"b3d777d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-37fbe23 e-con-full e-flex e-con e-child\" data-id=\"37fbe23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-606b37c cardimage elementor-widget elementor-widget-image\" data-id=\"606b37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/437424226-1024x683.jpeg\" class=\"attachment-large size-large wp-image-4459\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/437424226-1024x683.jpeg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/437424226-300x200.jpeg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/437424226-768x512.jpeg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/437424226-1536x1024.jpeg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/437424226-2048x1365.jpeg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83b43f elementor-widget elementor-widget-heading\" data-id=\"a83b43f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quelles sont les options th\u00e9rapeutiques pour un lip\u0153d\u00e8me ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a31768d elementor-widget elementor-widget-text-editor\" data-id=\"a31768d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La liposuccion dans le cadre d\u2019une op\u00e9ration du lip\u0153d\u00e8me est le seul traitement ayant un effet durable sur le lip\u0153d\u00e8me.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b36d637 cardbtn elementor-widget elementor-widget-button\" data-id=\"b36d637\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/das-lipodem\/#therapie\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8428f72 e-flex e-con-boxed e-con e-child\" data-id=\"8428f72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<article class=\"elementor-element elementor-element-69139eb cardstyle e-con-full e-flex e-con e-child\" data-id=\"69139eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0b5ecdc e-con-full e-flex e-con e-child\" data-id=\"0b5ecdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8856d5 cardimage elementor-widget elementor-widget-image\" data-id=\"c8856d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/553701298-1024x683.jpeg\" class=\"attachment-large size-large wp-image-4461\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/553701298-1024x683.jpeg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/553701298-300x200.jpeg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/553701298-768x512.jpeg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/553701298-1536x1025.jpeg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/553701298-2048x1366.jpeg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89cba09 elementor-widget elementor-widget-heading\" data-id=\"89cba09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Avez-vous des questions ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1551a6a elementor-widget elementor-widget-text-editor\" data-id=\"1551a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous trouverez de nombreuses informations sur le lip\u0153d\u00e8me et les m\u00e9thodes de traitement dans nos FAQ.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ef60b8 cardbtn elementor-widget elementor-widget-button\" data-id=\"5ef60b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/fr\/faq\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-4d1a518 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"4d1a518\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-50da966 e-con-full e-flex e-con e-child\" data-id=\"50da966\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72edf2d e-con-full e-flex e-con e-child\" data-id=\"72edf2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3fa5da elementor-widget elementor-widget-heading\" data-id=\"f3fa5da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Est-ce que j'ai<br>un lip\u0153d\u00e8me ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dce851 elementor-widget elementor-widget-text-editor\" data-id=\"0dce851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous vous sentez concern\u00e9e par plusieurs des troubles d\u00e9crits, nous vous recommandons de demander un diagnostic d\u00e9finitif aupr\u00e8s d\u2019un m\u00e9decin sp\u00e9cialis\u00e9 (phl\u00e9bologue\/lymphologue).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f7d9d0 elementor-widget elementor-widget-button\" data-id=\"7f7d9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.lipo.clinic\/fr\/test-du-lipoedeme\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Faire le test en 10 points <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-ed64f21 e-con-full elementor-hidden-desktop elementor-hidden-laptop sectionoverflow e-flex e-con e-parent\" data-id=\"ed64f21\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-15f6bac e-con-full respfullwidth e-flex e-con e-child\" data-id=\"15f6bac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f916b4 elementor-widget elementor-widget-image\" data-id=\"5f916b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"516\" src=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/habeicheinlipoedem2-1024x660.jpg\" class=\"attachment-large size-large wp-image-4510\" alt=\"\" srcset=\"https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/habeicheinlipoedem2-1024x660.jpg 1024w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/habeicheinlipoedem2-300x193.jpg 300w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/habeicheinlipoedem2-768x495.jpg 768w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/habeicheinlipoedem2-1536x990.jpg 1536w, https:\/\/www.lipo.clinic\/wp-content\/uploads\/2023\/02\/habeicheinlipoedem2-2048x1320.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e38e0b5 e-con-full e-flex e-con e-child\" data-id=\"e38e0b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e3015c elementor-widget elementor-widget-heading\" data-id=\"5e3015c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Est-ce que j'ai<br>un lip\u0153d\u00e8me ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21e7013 elementor-widget elementor-widget-text-editor\" data-id=\"21e7013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous vous sentez concern\u00e9e par plusieurs des troubles d\u00e9crits, nous vous recommandons de demander un diagnostic d\u00e9finitif aupr\u00e8s d\u2019un m\u00e9decin sp\u00e9cialis\u00e9 (phl\u00e9bologue\/lymphologue).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-477d667 elementor-widget elementor-widget-button\" data-id=\"477d667\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.lipo.clinic\/fr\/test-du-lipoedeme\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Faire le test en 10 points<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-3186f5c e-con-full sectionoverflow e-flex e-con e-parent\" data-id=\"3186f5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-33f7067 e-con-full e-flex e-con e-child\" data-id=\"33f7067\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd6481f e-flex e-con-boxed e-con e-child\" data-id=\"fd6481f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fbf832 elementor-widget elementor-widget-heading\" data-id=\"5fbf832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">UN TRAITEMENT HOLISTIQUE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d64a1ae elementor-widget elementor-widget-heading\" data-id=\"d64a1ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous \u00eates au c\u0153ur de notre action<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ef535c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6ef535c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>La LipoClinic s\u2019engage pour le traitement efficace du lip\u0153d\u00e8me et une recherche intensive sur le sujet.<\/strong> Il est particuli\u00e8rement important pour nous que l&#8217;environnement et les conditions psychologiques soient \u00e9galement pris en compte dans la th\u00e9rapie.<\/p><p>Nous connaissons votre odyss\u00e9e. Nous savons le manque de compr\u00e9hension et de connaissance de la maladie que vous avez d\u00fb affronter Les personnes concern\u00e9es se sentent souvent seules et mal comprises. Nous connaissons votre maladie depuis longtemps et voulons vous accompagner vers une nouvelle vie sans lip\u0153d\u00e8me.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3b3ec9 elementor-widget elementor-widget-button\" data-id=\"f3b3ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.lipo.clinic\/fr\/notre-approche\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-ba076b2 e-con-full e-flex e-con e-parent\" data-id=\"ba076b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f224c1 elementor-widget elementor-widget-shortcode\" data-id=\"6f224c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4620\" class=\"elementor elementor-4620 elementor-322 elementor-322\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-fd1b641 e-con-full e-flex e-con e-parent\" data-id=\"fd1b641\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fde405e e-con-full e-flex e-con e-parent\" data-id=\"fde405e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4a6fc elementor-widget elementor-widget-heading\" data-id=\"ef4a6fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93f4b70 elementor-widget elementor-widget-heading\" data-id=\"93f4b70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En bref et en clair<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef3ef52 elementor-widget elementor-widget-text-editor\" data-id=\"ef3ef52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Vous trouverez ici les r\u00e9ponses aux questions essentielles \u00e0 propos de la maladie du lip\u0153d\u00e8me et des possibilit\u00e9s de traitement.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95d13bd accordion elementor-widget elementor-widget-accordion\" data-id=\"95d13bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1571\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1571\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">BlockerItem \/ Kein Inhalt<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1571\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1571\">Contenu d\u2019accord\u00e9on<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1572\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1572\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>Douleurs<\/b><br>Comment d\u00e9crire les douleurs li\u00e9es au lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1572\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1572\"><p class=\"p1\">Lorsqu\u2019on demande aux femmes concern\u00e9es si elles ont des douleurs, elles r\u00e9pondent malheureusement souvent \u00ab non \u00bb. En effet, les troubles li\u00e9s au lip\u0153d\u00e8me ne sont pas ressentis comme des douleurs classiques, comme des c\u00e9phal\u00e9es, une br\u00fblure ou un lumbago, par exemple, et sont difficiles \u00e0 d\u00e9crire. Cependant, des jambes fatigu\u00e9es\/lourdes, une nette sensibilit\u00e9 au contact, une forte sensation de froid ou des tensions dans les jambes sont signes que vous devriez vous faire examiner par un m\u00e9decin sp\u00e9cialis\u00e9.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1573\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1573\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>Diagnostic<\/b><br>\u00c0 qui peuvent s\u2019adresser les personnes concern\u00e9es par un lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1573\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1573\"><p class=\"p1\">Diff\u00e9rents domaines m\u00e9dicaux sp\u00e9cialis\u00e9s sont aptes \u00e0 fournir un diagnostic du lip\u0153d\u00e8me. Parmi les sp\u00e9cialistes comp\u00e9tents dans le diagnostic du lip\u0153d\u00e8me se trouvent les phl\u00e9bologues, qui s\u2019occupent du diagnostic, du traitement et de la r\u00e9habilitation de maladies veineuses. Les lymphologues sont \u00e9galement aptes \u00e0 examiner des gonflements dans les tissus et \u00e0 diagnostiquer ou d\u2019exclure des maladies de la lymphe. Enfin, vous pouvez aussi vous adresser \u00e0 des angiologues, qui examinent les maladies art\u00e9rielles occlusives, les varices et les lymph\u0153d\u00e8mes et recommandent des m\u00e9thodes de traitement correspondantes.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1574\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1574\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>Traitement du lip\u0153d\u00e8me<\/b><br>Quelles sont les options th\u00e9rapeutiques d\u2019un lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1574\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1574\"><p class=\"p1\">La mesure primaire de traitement d\u2019un lip\u0153d\u00e8me est ce que l\u2019on appelle la \u00ab th\u00e9rapie de d\u00e9congestion conservatrice \u00bb, un traitement par un collant de compression rectiligne de 23 \u00e0 32 mmHg sur mesure et drainage lymphatique manuel (DLM). Si cette mesure ne suffit pas \u00e0 elle seule \u00e0 traiter un lip\u0153d\u00e8me, elle est cependant, en plus d\u2019une normalisation du poids par une activit\u00e9 sportive et une alimentation \u00e9quilibr\u00e9e, un facteur essentiel de r\u00e9duction des troubles.<\/p>\n<p class=\"p1\">Le seul traitement ayant un effet durable sur le lip\u0153d\u00e8me est la liposuccion, dans le cadre d\u2019une op\u00e9ration du lip\u0153d\u00e8me. Une r\u00e9alisation cons\u00e9quente et comp\u00e9tente de l\u2019op\u00e9ration permet g\u00e9n\u00e9ralement d\u2019attendre d\u2019excellents r\u00e9sultats pour un tr\u00e8s faible taux de complications. \u00c0 la LipoClinic, nous r\u00e9alisons chaque ann\u00e9e plus de 2 500 lipo-d\u00e9compressions,<b> <\/b>nous \u00e9levant ainsi au rang de leader mondial dans le traitement op\u00e9ratoire du lip\u0153d\u00e8me. La grande majorit\u00e9 de nos patientes b\u00e9n\u00e9ficient en l\u2019espace de seulement quelques jours d\u2019une nette r\u00e9duction de leurs douleurs. Les autres th\u00e9rapies, comme la compression ou le drainage lymphatique ne sont dans de nombreux cas plus n\u00e9cessaires au long terme.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1575\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1575\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>Le drainage lymphatique manuel (DLM)<\/b><br>Quel r\u00f4le joue le drainage lymphatique manuel dans le traitement du lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1575\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1575\"><p class=\"p1\">En pr\u00e9sence d\u2019un lip\u0153d\u00e8me, mais aussi d\u2019autres maladies, le liquide lymphatique s\u2019\u00e9coule difficilement du tissu. Cela provoque en fin de compte des probl\u00e8mes de congestion dans les mollets \u2013 l\u2019un des premiers sympt\u00f4mes typiques du lip\u0153d\u00e8me. De plus, \u00e9galement apr\u00e8s une op\u00e9ration, il y a une accumulation accrue d\u2019eau dans les tissus. Lorsque le diagnostic de lip\u0153d\u00e8me congestionn\u00e9 est pos\u00e9, on prescrit un drainage lymphatique manuel (DLM) comme partie de la th\u00e9rapie de d\u00e9congestion conservatrice. La plupart des lip\u0153d\u00e8mes n\u2019exigent pas une prescription permanente de DLM : un drainage lymphatique tous les jours ou tous les deux jours pendant six \u00e0 huit semaines permettent d\u2019atteindre de bons r\u00e9sultats et d\u2019amincir les jambes.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1576\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1576\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>La compression<\/b><br>Pourquoi les collants de compression sont-ils aussi importants pour les patientes du lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1576\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1576\"><p class=\"p1\">En pr\u00e9sence d\u2019un lip\u0153d\u00e8me, le tissu adipeux pathologique produit du liquide lymphatique en exc\u00e8s, qui s\u2019accumule dans le tissu et entra\u00eene ainsi une forte sollicitation du syst\u00e8me lymphatique. Un collant rectiligne \u00e0 maille plate taill\u00e9 sur mesure, obtenable sur prescription, permet, en combinaison avec une activit\u00e9 physique quotidienne, de d\u00e9congestionner le tissu par compression. Un collant rectiligne \u00e0 maille plate permet de mobiliser la lymphe et assiste le drainage du liquide accumul\u00e9 dans le tissu.<\/p>\n<p class=\"p1\">Le port d\u2019un collant de compression rectiligne \u00e0 maille plate est essentiel avant l\u2019op\u00e9ration du lip\u0153d\u00e8me, comme un tissu conjonctif des jambes d\u00e9congestionn\u00e9 et d\u00e9tendu est une pr\u00e9paration optimale \u00e0 une op\u00e9ration planifi\u00e9e. Un collant de compression rectiligne \u00e0 maille plate joue aussi un r\u00f4le important apr\u00e8s l\u2019op\u00e9ration, comme il masse et draine dynamiquement les gonflements, les h\u00e9matomes et l\u2019eau r\u00e9siduelle hors du tissu et fait rapidement dispara\u00eetre les h\u00e9matomes.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1577\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1577\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>Maille plate ou maille circulaire<\/b><br>Comment agissent les diff\u00e9rents collants de compression ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1577\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1577\"><p class=\"p1\">Un collant en maille circulaire est judicieux dans le cas d\u2019une maladie veineuse, par exemple suite \u00e0 une op\u00e9ration des varices. Il agit en comprimant les veines pour permettre aux valvules veineuses de se refermer.<\/p>\n<p class=\"p1\">Le port d\u2019un collant rectiligne \u00e0 maille plate fait partie des mesures du traitement conservateur du lip\u0153d\u00e8me. Il exerce une action permanente et d\u00e9congestionnante sur le tissu et la lymphe au cours des activit\u00e9s quotidiennes et apporte un soulagement en favorisant le drainage de l\u2019exc\u00e9dent de liquide.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1578\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1578\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>Grossesse<\/b><br>Quelle est l\u2019influence d\u2019une grossesse sur le lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1578\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1578\"><p>Une grossesse et les changements hormonaux qui y sont li\u00e9s peuvent contribuer \u00e0 une nette d\u00e9gradation d\u2019un lip\u0153d\u00e8me non trait\u00e9. <br \/>Mais, heureusement, il est de nos jours possible de diagnostiquer un lip\u0153d\u00e8me \u00e0 un stade pr\u00e9coce. De plus, les femmes ont actuellement tendance \u00e0 planifier une grossesse plus tardivement. Cela permet de planifier une op\u00e9ration du lip\u0153d\u00e8me en toute tranquillit\u00e9 pour \u00e9viter une aggravation pendant la grossesse.<br \/>Le moment optimal pour l\u2019op\u00e9ration est avant la premi\u00e8re grossesse. Selon notre exp\u00e9rience \u00e0 la LipoClinic, m\u00eame en cas de futures grossesses, il n\u2019y a que peu de probabilit\u00e9 de r\u00e9cidive d\u2019un lip\u0153d\u00e8me ou de prolif\u00e9ration des cellules adipeuses apr\u00e8s une op\u00e9ration enti\u00e8rement achev\u00e9e.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1579\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1579\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>L\u2019activit\u00e9 physique et le sport<\/b><br>Quel r\u00f4le jouent l\u2019activit\u00e9 physique et le sport dans la vie de patientes du lip\u0153d\u00e8me ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1579\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1579\"><p class=\"p1\">Ni le sport, ni les r\u00e9gimes ne permettent d\u2019\u00e9liminer la maladie du lip\u0153d\u00e8me, cependant, le sport reste un \u00e9l\u00e9ment essentiel dans le traitement du lip\u0153d\u00e8me. Pour les femmes atteintes du lip\u0153d\u00e8me, maintenir une activit\u00e9 physique est d\u2019une importance fondamentale. Une activit\u00e9 physique suppl\u00e9mentaire (en font \u00e9galement partie, par exemple, de longues promenades, la gymnastique aquatique et la mont\u00e9e d\u2019escalier) fait tout simplement du bien au corps et \u00e0 l\u2019esprit. En d\u2019autres termes, si une activit\u00e9 sportive ne suffit pas \u00e0 combattre le lip\u0153d\u00e8me, elle vous donnera durablement une nouvelle qualit\u00e9 de vie. Vous devez prendre du plaisir \u00e0 bouger et avoir une vie active. Simultan\u00e9ment, le sport permet de r\u00e9duire plus facilement d\u2019autres zones du corps non touch\u00e9es par le lip\u0153d\u00e8me. Il permet d\u2019arriver \u00e0 une satisfaction globale ainsi que, au sens propre, \u00e0 une nouvelle l\u00e9g\u00e8ret\u00e9. En compl\u00e9ment, une alimentation saine et \u00e9quilibr\u00e9e est \u00e9galement importante.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-15710\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-15710\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><b>L\u2019alimentation<\/b><br>Comment une alimentation \u00e9quilibr\u00e9e peut-elle contribuer au succ\u00e8s de votre traitement ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-15710\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-15710\"><p class=\"p1\">En plus de la compression, de l\u2019activit\u00e9 physique et de l\u2019op\u00e9ration, l\u2019alimentation et, en cons\u00e9quence, le poids de femmes atteintes de lip\u0153d\u00e8me, est un facteur important. L\u2019objectif n\u2019est pas de perdre du poids rapidement, mais d\u2019accro\u00eetre le bien-\u00eatre et la forme en adoptant une alimentation saine et \u00e9quilibr\u00e9e. Une r\u00e9duction du poids reste dans de nombreux cas quand m\u00eame important pour le succ\u00e8s global du traitement. Adoptez une alimentation raisonn\u00e9e, saine et \u00e9quilibr\u00e9e. \u00c9liminez le sucre industriel, les aliments transform\u00e9s et les produits de commodit\u00e9 de votre menu et misez autant que possible sur une alimentation bas\u00e9e sur des produits entiers. Observez-vous vous-m\u00eame et \u00e9coutez votre corps, vous trouverez certainement la forme d\u2019alimentation qui vous convient. Vous pourrez ainsi contribuer vous-m\u00eame au traitement des sympt\u00f4mes de votre lip\u0153d\u00e8me et am\u00e9liorer durablement votre qualit\u00e9 de vie.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"BlockerItem \\\/ Kein Inhalt\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Contenu d\\u2019accord\\u00e9on\"}},{\"@type\":\"Question\",\"name\":\"DouleursComment d\\u00e9crire les douleurs li\\u00e9es au lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">Lorsqu\\u2019on demande aux femmes concern\\u00e9es si elles ont des douleurs, elles r\\u00e9pondent malheureusement souvent \\u00ab non \\u00bb. En effet, les troubles li\\u00e9s au lip\\u0153d\\u00e8me ne sont pas ressentis comme des douleurs classiques, comme des c\\u00e9phal\\u00e9es, une br\\u00fblure ou un lumbago, par exemple, et sont difficiles \\u00e0 d\\u00e9crire. Cependant, des jambes fatigu\\u00e9es\\\/lourdes, une nette sensibilit\\u00e9 au contact, une forte sensation de froid ou des tensions dans les jambes sont signes que vous devriez vous faire examiner par un m\\u00e9decin sp\\u00e9cialis\\u00e9.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Diagnostic\\u00c0 qui peuvent s\\u2019adresser les personnes concern\\u00e9es par un lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">Diff\\u00e9rents domaines m\\u00e9dicaux sp\\u00e9cialis\\u00e9s sont aptes \\u00e0 fournir un diagnostic du lip\\u0153d\\u00e8me. Parmi les sp\\u00e9cialistes comp\\u00e9tents dans le diagnostic du lip\\u0153d\\u00e8me se trouvent les phl\\u00e9bologues, qui s\\u2019occupent du diagnostic, du traitement et de la r\\u00e9habilitation de maladies veineuses. Les lymphologues sont \\u00e9galement aptes \\u00e0 examiner des gonflements dans les tissus et \\u00e0 diagnostiquer ou d\\u2019exclure des maladies de la lymphe. Enfin, vous pouvez aussi vous adresser \\u00e0 des angiologues, qui examinent les maladies art\\u00e9rielles occlusives, les varices et les lymph\\u0153d\\u00e8mes et recommandent des m\\u00e9thodes de traitement correspondantes.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Traitement du lip\\u0153d\\u00e8meQuelles sont les options th\\u00e9rapeutiques d\\u2019un lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">La mesure primaire de traitement d\\u2019un lip\\u0153d\\u00e8me est ce que l\\u2019on appelle la \\u00ab th\\u00e9rapie de d\\u00e9congestion conservatrice \\u00bb, un traitement par un collant de compression rectiligne de 23 \\u00e0 32 mmHg sur mesure et drainage lymphatique manuel (DLM). Si cette mesure ne suffit pas \\u00e0 elle seule \\u00e0 traiter un lip\\u0153d\\u00e8me, elle est cependant, en plus d\\u2019une normalisation du poids par une activit\\u00e9 sportive et une alimentation \\u00e9quilibr\\u00e9e, un facteur essentiel de r\\u00e9duction des troubles.<\\\/p>\\n<p class=\\\"p1\\\">Le seul traitement ayant un effet durable sur le lip\\u0153d\\u00e8me est la liposuccion, dans le cadre d\\u2019une op\\u00e9ration du lip\\u0153d\\u00e8me. Une r\\u00e9alisation cons\\u00e9quente et comp\\u00e9tente de l\\u2019op\\u00e9ration permet g\\u00e9n\\u00e9ralement d\\u2019attendre d\\u2019excellents r\\u00e9sultats pour un tr\\u00e8s faible taux de complications. \\u00c0 la LipoClinic, nous r\\u00e9alisons chaque ann\\u00e9e plus de 2 500 lipo-d\\u00e9compressions,<b> <\\\/b>nous \\u00e9levant ainsi au rang de leader mondial dans le traitement op\\u00e9ratoire du lip\\u0153d\\u00e8me. La grande majorit\\u00e9 de nos patientes b\\u00e9n\\u00e9ficient en l\\u2019espace de seulement quelques jours d\\u2019une nette r\\u00e9duction de leurs douleurs. Les autres th\\u00e9rapies, comme la compression ou le drainage lymphatique ne sont dans de nombreux cas plus n\\u00e9cessaires au long terme.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Le drainage lymphatique manuel (DLM)Quel r\\u00f4le joue le drainage lymphatique manuel dans le traitement du lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">En pr\\u00e9sence d\\u2019un lip\\u0153d\\u00e8me, mais aussi d\\u2019autres maladies, le liquide lymphatique s\\u2019\\u00e9coule difficilement du tissu. Cela provoque en fin de compte des probl\\u00e8mes de congestion dans les mollets \\u2013 l\\u2019un des premiers sympt\\u00f4mes typiques du lip\\u0153d\\u00e8me. De plus, \\u00e9galement apr\\u00e8s une op\\u00e9ration, il y a une accumulation accrue d\\u2019eau dans les tissus. Lorsque le diagnostic de lip\\u0153d\\u00e8me congestionn\\u00e9 est pos\\u00e9, on prescrit un drainage lymphatique manuel (DLM) comme partie de la th\\u00e9rapie de d\\u00e9congestion conservatrice. La plupart des lip\\u0153d\\u00e8mes n\\u2019exigent pas une prescription permanente de DLM : un drainage lymphatique tous les jours ou tous les deux jours pendant six \\u00e0 huit semaines permettent d\\u2019atteindre de bons r\\u00e9sultats et d\\u2019amincir les jambes.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"La compressionPourquoi les collants de compression sont-ils aussi importants pour les patientes du lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">En pr\\u00e9sence d\\u2019un lip\\u0153d\\u00e8me, le tissu adipeux pathologique produit du liquide lymphatique en exc\\u00e8s, qui s\\u2019accumule dans le tissu et entra\\u00eene ainsi une forte sollicitation du syst\\u00e8me lymphatique. Un collant rectiligne \\u00e0 maille plate taill\\u00e9 sur mesure, obtenable sur prescription, permet, en combinaison avec une activit\\u00e9 physique quotidienne, de d\\u00e9congestionner le tissu par compression. Un collant rectiligne \\u00e0 maille plate permet de mobiliser la lymphe et assiste le drainage du liquide accumul\\u00e9 dans le tissu.<\\\/p>\\n<p class=\\\"p1\\\">Le port d\\u2019un collant de compression rectiligne \\u00e0 maille plate est essentiel avant l\\u2019op\\u00e9ration du lip\\u0153d\\u00e8me, comme un tissu conjonctif des jambes d\\u00e9congestionn\\u00e9 et d\\u00e9tendu est une pr\\u00e9paration optimale \\u00e0 une op\\u00e9ration planifi\\u00e9e. Un collant de compression rectiligne \\u00e0 maille plate joue aussi un r\\u00f4le important apr\\u00e8s l\\u2019op\\u00e9ration, comme il masse et draine dynamiquement les gonflements, les h\\u00e9matomes et l\\u2019eau r\\u00e9siduelle hors du tissu et fait rapidement dispara\\u00eetre les h\\u00e9matomes.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Maille plate ou maille circulaireComment agissent les diff\\u00e9rents collants de compression ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">Un collant en maille circulaire est judicieux dans le cas d\\u2019une maladie veineuse, par exemple suite \\u00e0 une op\\u00e9ration des varices. Il agit en comprimant les veines pour permettre aux valvules veineuses de se refermer.<\\\/p>\\n<p class=\\\"p1\\\">Le port d\\u2019un collant rectiligne \\u00e0 maille plate fait partie des mesures du traitement conservateur du lip\\u0153d\\u00e8me. Il exerce une action permanente et d\\u00e9congestionnante sur le tissu et la lymphe au cours des activit\\u00e9s quotidiennes et apporte un soulagement en favorisant le drainage de l\\u2019exc\\u00e9dent de liquide.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"GrossesseQuelle est l\\u2019influence d\\u2019une grossesse sur le lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Une grossesse et les changements hormonaux qui y sont li\\u00e9s peuvent contribuer \\u00e0 une nette d\\u00e9gradation d\\u2019un lip\\u0153d\\u00e8me non trait\\u00e9. <br \\\/>Mais, heureusement, il est de nos jours possible de diagnostiquer un lip\\u0153d\\u00e8me \\u00e0 un stade pr\\u00e9coce. De plus, les femmes ont actuellement tendance \\u00e0 planifier une grossesse plus tardivement. Cela permet de planifier une op\\u00e9ration du lip\\u0153d\\u00e8me en toute tranquillit\\u00e9 pour \\u00e9viter une aggravation pendant la grossesse.<br \\\/>Le moment optimal pour l\\u2019op\\u00e9ration est avant la premi\\u00e8re grossesse. Selon notre exp\\u00e9rience \\u00e0 la LipoClinic, m\\u00eame en cas de futures grossesses, il n\\u2019y a que peu de probabilit\\u00e9 de r\\u00e9cidive d\\u2019un lip\\u0153d\\u00e8me ou de prolif\\u00e9ration des cellules adipeuses apr\\u00e8s une op\\u00e9ration enti\\u00e8rement achev\\u00e9e.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"L\\u2019activit\\u00e9 physique et le sportQuel r\\u00f4le jouent l\\u2019activit\\u00e9 physique et le sport dans la vie de patientes du lip\\u0153d\\u00e8me ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">Ni le sport, ni les r\\u00e9gimes ne permettent d\\u2019\\u00e9liminer la maladie du lip\\u0153d\\u00e8me, cependant, le sport reste un \\u00e9l\\u00e9ment essentiel dans le traitement du lip\\u0153d\\u00e8me. Pour les femmes atteintes du lip\\u0153d\\u00e8me, maintenir une activit\\u00e9 physique est d\\u2019une importance fondamentale. Une activit\\u00e9 physique suppl\\u00e9mentaire (en font \\u00e9galement partie, par exemple, de longues promenades, la gymnastique aquatique et la mont\\u00e9e d\\u2019escalier) fait tout simplement du bien au corps et \\u00e0 l\\u2019esprit. En d\\u2019autres termes, si une activit\\u00e9 sportive ne suffit pas \\u00e0 combattre le lip\\u0153d\\u00e8me, elle vous donnera durablement une nouvelle qualit\\u00e9 de vie. Vous devez prendre du plaisir \\u00e0 bouger et avoir une vie active. Simultan\\u00e9ment, le sport permet de r\\u00e9duire plus facilement d\\u2019autres zones du corps non touch\\u00e9es par le lip\\u0153d\\u00e8me. Il permet d\\u2019arriver \\u00e0 une satisfaction globale ainsi que, au sens propre, \\u00e0 une nouvelle l\\u00e9g\\u00e8ret\\u00e9. En compl\\u00e9ment, une alimentation saine et \\u00e9quilibr\\u00e9e est \\u00e9galement importante.<\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"L\\u2019alimentationComment une alimentation \\u00e9quilibr\\u00e9e peut-elle contribuer au succ\\u00e8s de votre traitement ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p class=\\\"p1\\\">En plus de la compression, de l\\u2019activit\\u00e9 physique et de l\\u2019op\\u00e9ration, l\\u2019alimentation et, en cons\\u00e9quence, le poids de femmes atteintes de lip\\u0153d\\u00e8me, est un facteur important. L\\u2019objectif n\\u2019est pas de perdre du poids rapidement, mais d\\u2019accro\\u00eetre le bien-\\u00eatre et la forme en adoptant une alimentation saine et \\u00e9quilibr\\u00e9e. Une r\\u00e9duction du poids reste dans de nombreux cas quand m\\u00eame important pour le succ\\u00e8s global du traitement. Adoptez une alimentation raisonn\\u00e9e, saine et \\u00e9quilibr\\u00e9e. \\u00c9liminez le sucre industriel, les aliments transform\\u00e9s et les produits de commodit\\u00e9 de votre menu et misez autant que possible sur une alimentation bas\\u00e9e sur des produits entiers. Observez-vous vous-m\\u00eame et \\u00e9coutez votre corps, vous trouverez certainement la forme d\\u2019alimentation qui vous convient. Vous pourrez ainsi contribuer vous-m\\u00eame au traitement des sympt\\u00f4mes de votre lip\\u0153d\\u00e8me et am\\u00e9liorer durablement votre qualit\\u00e9 de vie.<\\\/p>\\n\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-4e76f58 e-con-full elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"4e76f58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-161da97 elementor-widget elementor-widget-heading\" data-id=\"161da97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"> <strong>Blog &amp; Posts<\/strong><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11be409 elementor-grid-4 elementor-grid-laptop-3 elementor-grid-mobile-1 elementor-grid-tablet-2 elementor-widget elementor-widget-loop-grid\" data-id=\"11be409\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:4927,&quot;columns&quot;:4,&quot;masonry&quot;:&quot;yes&quot;,&quot;pagination_type&quot;:&quot;load_more_on_click&quot;,&quot;columns_laptop&quot;:3,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;columns_mobile&quot;:1,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-4927\">.elementor-4927 .elementor-element.elementor-element-3435779{--display:flex;--margin-top:0em;--margin-bottom:2em;--margin-left:0em;--margin-right:0em;--padding-top:0em;--padding-bottom:0em;--padding-left:0em;--padding-right:0em;}.elementor-4927 .elementor-element.elementor-element-3435779:hover{border-style:none;}.elementor-4927 .elementor-element.elementor-element-3435779, .elementor-4927 .elementor-element.elementor-element-3435779::before{--border-transition:0.3s;}.elementor-4927 .elementor-element.elementor-element-f5238e8{--display:flex;--gap:1em 1em;--row-gap:1em;--column-gap:1em;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-4927 .elementor-element.elementor-element-f5238e8:hover{border-style:solid;border-width:0px 0px 0px 0px;--border-top-width:0px;--border-right-width:0px;--border-bottom-width:0px;--border-left-width:0px;border-color:var( --e-global-color-1865ca8 );--border-color:var( --e-global-color-1865ca8 );}.elementor-4927 .elementor-element.elementor-element-f5238e8, .elementor-4927 .elementor-element.elementor-element-f5238e8::before{--border-transition:0.3s;}.elementor-4927 .elementor-element.elementor-element-4839acd img{width:100%;border-style:none;}.elementor-4927 .elementor-element.elementor-element-bd38b15 .elementor-widget-container{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-4927 .elementor-element.elementor-element-265b752 > .elementor-widget-container{padding:0px 0px 0px 0px;}@media(max-width:1366px){.elementor-4927 .elementor-element.elementor-element-bd38b15 .elementor-widget-container{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}@media(max-width:1024px){.elementor-4927 .elementor-element.elementor-element-bd38b15 .elementor-widget-container{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}@media(max-width:767px){.elementor-4927 .elementor-element.elementor-element-bd38b15 .elementor-widget-container{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4927\" class=\"elementor elementor-4927 elementor-329 elementor-329 e-loop-item e-loop-item-26044 post-26044 post type-post status-publish format-standard hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<article class=\"elementor-element elementor-element-3435779 cardstyle e-con-full e-flex e-con e-parent\" data-id=\"3435779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f5238e8 e-con-full e-flex e-con e-child\" data-id=\"f5238e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c6d6a elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"a5c6d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Journ\u00e9e portes ouvertes \u00e0 M\u00fclheim &#8211; 04.07.2026 | 10 heures | Zeppelinstra\u00dfe 321, M\u00fclheim an der Ruhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265b752 cardbtn elementor-widget elementor-widget-button\" data-id=\"265b752\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/fr\/journee-portes-ouvertes-a-mulheim-04-07-2026-10-heures-zeppelinstrase-321-mulheim-an-der-ruhr-30\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4927\" class=\"elementor elementor-4927 elementor-329 elementor-329 e-loop-item e-loop-item-26040 post-26040 post type-post status-publish format-standard hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<article class=\"elementor-element elementor-element-3435779 cardstyle e-con-full e-flex e-con e-parent\" data-id=\"3435779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f5238e8 e-con-full e-flex e-con e-child\" data-id=\"f5238e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c6d6a elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"a5c6d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Journ\u00e9e portes ouvertes \u00e0 M\u00fclheim &#8211; 04.07.2026 | 10 heures | Zeppelinstra\u00dfe 321, M\u00fclheim an der Ruhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265b752 cardbtn elementor-widget elementor-widget-button\" data-id=\"265b752\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/fr\/journee-portes-ouvertes-a-mulheim-04-07-2026-10-heures-zeppelinstrase-321-mulheim-an-der-ruhr-29\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4927\" class=\"elementor elementor-4927 elementor-329 elementor-329 e-loop-item e-loop-item-25902 post-25902 post type-post status-publish format-standard hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<article class=\"elementor-element elementor-element-3435779 cardstyle e-con-full e-flex e-con e-parent\" data-id=\"3435779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f5238e8 e-con-full e-flex e-con e-child\" data-id=\"f5238e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c6d6a elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"a5c6d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Journ\u00e9e portes ouvertes \u00e0 M\u00fclheim &#8211; 04.07.2026 | 10 heures | Zeppelinstra\u00dfe 321, M\u00fclheim an der Ruhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265b752 cardbtn elementor-widget elementor-widget-button\" data-id=\"265b752\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/fr\/journee-portes-ouvertes-a-mulheim-04-07-2026-10-heures-zeppelinstrase-321-mulheim-an-der-ruhr-28\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"4927\" class=\"elementor elementor-4927 elementor-329 elementor-329 e-loop-item e-loop-item-25888 post-25888 post type-post status-publish format-standard hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<article class=\"elementor-element elementor-element-3435779 cardstyle e-con-full e-flex e-con e-parent\" data-id=\"3435779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f5238e8 e-con-full e-flex e-con e-child\" data-id=\"f5238e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c6d6a elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"a5c6d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Journ\u00e9e portes ouvertes \u00e0 M\u00fclheim &#8211; 04.07.2026 | 10 heures | Zeppelinstra\u00dfe 321, M\u00fclheim an der Ruhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265b752 cardbtn elementor-widget elementor-widget-button\" data-id=\"265b752\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lipo.clinic\/fr\/journee-portes-ouvertes-a-mulheim-04-07-2026-10-heures-zeppelinstrase-321-mulheim-an-der-ruhr-27\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lire la suite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-spinner\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M304 48c0 26.51-21.49 48-48 48s-48-21.49-48-48 21.49-48 48-48 48 21.49 48 48zm-48 368c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48zm208-208c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48zM96 256c0-26.51-21.49-48-48-48S0 229.49 0 256s21.49 48 48 48 48-21.49 48-48zm12.922 99.078c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48c0-26.509-21.491-48-48-48zm294.156 0c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48c0-26.509-21.49-48-48-48zM108.922 60.922c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.491-48-48-48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"45\" data-next-page=\"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/pages\/4618\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"e-loop__load-more elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"e-load-more-message\">Ne plus afficher de messages.<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e1c9467 e-flex e-con-boxed e-con e-parent\" data-id=\"e1c9467\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc12c7d elementor-widget__width-inherit elementor-widget elementor-widget-html\" data-id=\"bc12c7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Elfsight Instagram Feed | Untitled Instagram Feed -->\r\n<script src=\"https:\/\/elfsightcdn.com\/platform.js\" async=\"\"><\/script>\r\n<div class=\"elfsight-app-c6caea55-1d1c-45e6-9241-2543022c34b2\" data-elfsight-app-lazy=\"\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa77f85 elementor-widget elementor-widget-spacer\" data-id=\"aa77f85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Connu de : La principale clinique du lip\u0153d\u00e8me pour le diagnostic et le traitement du lip\u0153d\u00e8me Nouvelle libert\u00e9 pour le corps et l&#8217;esprit Environ une femme sur dix est touch\u00e9e par le lip\u0153d\u00e8me \u2013 une \u00ab maladie que tout le monde voit, mais que presque personne ne conna\u00eet \u00bb. Pionni\u00e8re dans le traitement chirurgical du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17439,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4618","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/pages\/4618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/comments?post=4618"}],"version-history":[{"count":23,"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/pages\/4618\/revisions"}],"predecessor-version":[{"id":24917,"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/pages\/4618\/revisions\/24917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/media\/17439"}],"wp:attachment":[{"href":"https:\/\/www.lipo.clinic\/fr\/wp-json\/wp\/v2\/media?parent=4618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}